{"id":549,"date":"2026-05-23T16:28:33","date_gmt":"2026-05-23T14:28:33","guid":{"rendered":"https:\/\/tecfin.mx-medienagentur.com\/?page_id=549"},"modified":"2026-05-31T01:14:02","modified_gmt":"2026-05-30T23:14:02","slug":"bodenfolie","status":"publish","type":"page","link":"https:\/\/tecfin.de\/tr\/bodenfolie\/","title":{"rendered":"Zemin Folyesi"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"549\" class=\"elementor elementor-549\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-d52b2cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d52b2cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48fa10e\" data-id=\"48fa10e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e7a780 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9e7a780\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">End\u00fcstriyel Zeminler \u0130\u00e7in Zemin Folyesi<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a4ff0c elementor-widget elementor-widget-spacer\" data-id=\"8a4ff0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ecb9c39 e-flex e-con-boxed e-con e-parent\" data-id=\"5ecb9c39\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7785fc42 e-con-full e-flex e-con e-child\" data-id=\"7785fc42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-71425326 e-con-full e-flex e-con e-child\" data-id=\"71425326\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36932f20 elementor-widget elementor-widget-heading\" data-id=\"36932f20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dayan\u0131kl\u0131 beton y\u00fczeyler i\u00e7in g\u00fcvenilir ay\u0131r\u0131c\u0131 ve kayd\u0131r\u0131c\u0131 katman<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a73d928 elementor-widget elementor-widget-text-editor\" data-id=\"1a73d928\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTECFIN Tip 200 zemin folyesi, end\u00fcstriyel zemin uygulamalar\u0131nda kullan\u0131lmak \u00fczere \u00f6zel olarak geli\u015ftirilmi\u015ftir. Zemin ile beton aras\u0131nda ay\u0131r\u0131c\u0131 katman g\u00f6revi g\u00f6r\u00fcr ve uygulama ile sertle\u015fme s\u00fcrecinde dengeli ko\u015fullar\u0131n korunmas\u0131na yard\u0131mc\u0131 olur.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c65988 elementor-widget elementor-widget-button\" data-id=\"74c65988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/tecfin.de\/wp-content\/uploads\/5-TECFIN-Bodenfolie-Produktdatenblatt_BB.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PE Folye \u00dcr\u00fcn Veri Sayfas\u0131<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ab37a3d e-con-full e-flex e-con e-child\" data-id=\"1ab37a3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33f7a26f elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"33f7a26f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;200&quot;,&quot;_animation&quot;:&quot;bounceIn&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"ti ti-plus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d17072b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7d17072b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;400&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"2064\" src=\"https:\/\/tecfin.de\/wp-content\/uploads\/247910888034-scaled.jpg\" class=\"attachment-full size-full wp-image-551\" alt=\"\" srcset=\"https:\/\/tecfin.de\/wp-content\/uploads\/247910888034-scaled.jpg 2560w, https:\/\/tecfin.de\/wp-content\/uploads\/247910888034-300x242.jpg 300w, https:\/\/tecfin.de\/wp-content\/uploads\/247910888034-1024x826.jpg 1024w, https:\/\/tecfin.de\/wp-content\/uploads\/247910888034-768x619.jpg 768w, https:\/\/tecfin.de\/wp-content\/uploads\/247910888034-1536x1239.jpg 1536w, https:\/\/tecfin.de\/wp-content\/uploads\/247910888034-2048x1651.jpg 2048w, https:\/\/tecfin.de\/wp-content\/uploads\/247910888034-650x524.jpg 650w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c0a26c0 elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"2c0a26c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;200&quot;,&quot;_animation&quot;:&quot;bounceIn&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"ti ti-plus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e689197 e-flex e-con-boxed e-con e-parent\" data-id=\"2e689197\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e887ef7 e-con-full e-flex e-con e-child\" data-id=\"6e887ef7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-33a534e0 e-con-full e-flex e-con e-child\" data-id=\"33a534e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bda97a3 elementor-widget elementor-widget-heading\" data-id=\"5bda97a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zemin folyesinin end\u00fcstriyel zeminlerde \u00f6nemli olmas\u0131n\u0131n nedenleri<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-763544ef e-con-full e-flex e-con e-child\" data-id=\"763544ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41fa3981 elementor-widget elementor-widget-text-editor\" data-id=\"41fa3981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tPE zemin folyesi olarak, alt yap\u0131 malzemelerinin beton i\u00e7ine kar\u0131\u015fmas\u0131n\u0131 azaltmaya ve hidratasyon s\u00fcrecinde su kayb\u0131n\u0131 \u00f6nlemeye yard\u0131mc\u0131 olur. Ayn\u0131 zamanda betonun r\u00f6tre s\u00fcrecini destekler ve y\u00fcksek kaliteli end\u00fcstriyel zeminler i\u00e7in temiz bir temel olu\u015fturur.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-578a5d8 e-con-full e-flex e-con e-child\" data-id=\"578a5d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48a069 ui-e-icon-right elementor-widget__width-inherit ui-e-left elementor-align-left elementor-invisible elementor-widget elementor-widget-uicore-icon-list\" data-id=\"48a069\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;300&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"uicore-icon-list.default\">\n\t\t\t\t\t        <ul>\n                            <li >\n\n                    <div class=\"ui-e-wrap\">\n                    \n                    \n                    <div class=\"ui-e-content\">\n                        <h4 class=\"ui-e-title\">\n                            Alt zeminle kar\u0131\u015fmay\u0131 \u00f6nler                        <\/h4>\n                        <p class=\"ui-e-text\"> Zemin folyesi, beton ile alt yap\u0131y\u0131 g\u00fcvenilir \u015fekilde birbirinden ay\u0131r\u0131r. B\u00f6ylece alt zemindeki malzemelerin beton y\u00fczeyine kar\u0131\u015fmas\u0131 \u00f6nlenir. <\/p>\n                    <\/div>\n\n                    \n                    <\/div>\n                <\/li>\n                            <li >\n\n                    <div class=\"ui-e-wrap\">\n                    \n                    \n                    <div class=\"ui-e-content\">\n                        <h4 class=\"ui-e-title\">\n                            Hidratasyon s\u00fcrecini destekler                        <\/h4>\n                        <p class=\"ui-e-text\"> Sertle\u015fme s\u00fcrecinde kontroll\u00fc nem b\u00fcy\u00fck \u00f6nem ta\u015f\u0131r. Folye, gerekli suyun alt zemine s\u0131zmas\u0131n\u0131 azalt\u0131r. <\/p>\n                    <\/div>\n\n                    \n                    <\/div>\n                <\/li>\n                    <\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2867a149 ui-e-icon-right elementor-widget__width-inherit ui-e-left elementor-align-left elementor-invisible elementor-widget elementor-widget-uicore-icon-list\" data-id=\"2867a149\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;300&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"uicore-icon-list.default\">\n\t\t\t\t\t        <ul>\n                            <li >\n\n                    <div class=\"ui-e-wrap\">\n                    \n                    \n                    <div class=\"ui-e-content\">\n                        <h4 class=\"ui-e-title\">\n                            Uygulama s\u0131ras\u0131nda dengeli ko\u015fullar sa\u011flar                        <\/h4>\n                        <p class=\"ui-e-text\"> Uygun bir ay\u0131r\u0131c\u0131 katman, beton plakas\u0131n\u0131n alt\u0131nda dengeli ko\u015fullar olu\u015fturur ve temiz bir uygulamaya katk\u0131 sa\u011flar. <\/p>\n                    <\/div>\n\n                    \n                    <\/div>\n                <\/li>\n                            <li >\n\n                    <div class=\"ui-e-wrap\">\n                    \n                    \n                    <div class=\"ui-e-content\">\n                        <h4 class=\"ui-e-title\">\n                            R\u00f6tre davran\u0131\u015f\u0131n\u0131 destekler                        <\/h4>\n                        <p class=\"ui-e-text\"> Folye ayn\u0131 zamanda kayd\u0131r\u0131c\u0131 katman g\u00f6revi g\u00f6r\u00fcr ve kuruma s\u0131ras\u0131nda betonun do\u011fal r\u00f6tre s\u00fcrecini destekler. <\/p>\n                    <\/div>\n\n                    \n                    <\/div>\n                <\/li>\n                    <\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79ff6940 e-flex e-con-boxed e-con e-parent\" data-id=\"79ff6940\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-72147dd3 e-con-full e-flex e-con e-child\" data-id=\"72147dd3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-317e48ab elementor-widget elementor-widget-heading\" data-id=\"317e48ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pratik bir \u00e7\u00f6z\u00fcm olarak TECFIN zemin folyesi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d11627c elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7d11627c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;300&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTECFIN Tip 200 zemin folyesi, modern end\u00fcstriyel zeminlerin gereksinimlerine uygun olarak geli\u015ftirilmi\u015f olup beton uygulamalar\u0131ndaki farkl\u0131 kullan\u0131m alanlar\u0131 i\u00e7in uygundur.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cf4f916 ui-e-icon-right ui-e-left elementor-align-left elementor-invisible elementor-widget elementor-widget-uicore-icon-list\" data-id=\"7cf4f916\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;300&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"uicore-icon-list.default\">\n\t\t\t\t\t        <ul>\n                            <li >\n\n                    <div class=\"ui-e-wrap\">\n                    \n                    \n                    <div class=\"ui-e-content\">\n                        <h4 class=\"ui-e-title\">\n                            Kan\u0131tlanm\u0131\u015f standart \u00e7\u00f6z\u00fcm olarak Tip 200                        <\/h4>\n                        <p class=\"ui-e-text\"> Zemin folyesi, end\u00fcstriyel zemin ve beton uygulamalar\u0131ndaki yayg\u0131n sekt\u00f6r gereksinimlerini kar\u015f\u0131lar ve PE tolerans folyesi olarak kullan\u0131l\u0131r. <\/p>\n                    <\/div>\n\n                    \n                    <\/div>\n                <\/li>\n                            <li >\n\n                    <div class=\"ui-e-wrap\">\n                    \n                    \n                    <div class=\"ui-e-content\">\n                        <h4 class=\"ui-e-title\">\n                            \u015eantiye ko\u015fullar\u0131 i\u00e7in dayan\u0131kl\u0131 malzeme                        <\/h4>\n                        <p class=\"ui-e-text\"> Folye, geri d\u00f6n\u00fc\u015ft\u00fcr\u00fclm\u00fc\u015f i\u00e7erik bar\u0131nd\u0131ran polietilen ve kopolimerlerden \u00fcretilmi\u015ftir ve g\u00fcnl\u00fck \u015fantiye kullan\u0131m\u0131 i\u00e7in uygundur. <\/p>\n                    <\/div>\n\n                    \n                    <\/div>\n                <\/li>\n                            <li >\n\n                    <div class=\"ui-e-wrap\">\n                    \n                    \n                    <div class=\"ui-e-content\">\n                        <h4 class=\"ui-e-title\">\n                            Verimli \u00e7al\u0131\u015fma i\u00e7in b\u00fcy\u00fck rulo formatlar\u0131                        <\/h4>\n                        <p class=\"ui-e-text\"> 4 metre rulo geni\u015fli\u011fi sayesinde geni\u015f alanlar ekonomik ve zaman tasarruflu \u015fekilde kaplanabilir. <\/p>\n                    <\/div>\n\n                    \n                    <\/div>\n                <\/li>\n                    <\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a998d22 e-flex e-con-boxed e-con e-parent\" data-id=\"6a998d22\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59403227 ui-e-a-animate elementor-invisible elementor-widget elementor-widget-highlighted-text\" data-id=\"59403227\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;240&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"highlighted-text.default\">\n\t\t\t\t\t        <h2 class=\"ui-e--highlighted-text\">\n            <span class=\"ui-e-headline-text elementor-repeater-item-bace23b\">S\u0131k\u00e7a Sorulan<\/span><span class=\"ui-e-headline-text elementor-repeater-item-3c183ef ui-e-headline-color\">\n\t\t\t\t\t\t\t\t\t<span class=\"whitespace\"><\/span>\n                                    <span>\n                                        <span class=\"ui-e-headline-text ui-e-headline-highlighted\">Sorular.<\/span><span class=\"uicore-svg-wrapper\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 500 150\" preserveaspectratio=\"none\"><\/svg><\/span><\/span> <span class=\"whitespace\"> <\/span><\/span>        <\/h2>\n    \t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-701ccf60 ui-e-animation-acc-overshadow ui-e-animation-ico-slide elementor-invisible elementor-widget elementor-widget-uicore-accordion\" data-id=\"701ccf60\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:&quot;240&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;accordion_animation&quot;:&quot;ui-e-animation-acc-overshadow&quot;,&quot;collapsible&quot;:&quot;true&quot;,&quot;active_hash&quot;:&quot;no&quot;}\" data-widget_type=\"uicore-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"ui-e-accordion\" >\n\n                            <div class=\"ui-e-accordion-item ui-e-item ui-open\" role=\"button\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"ui-e-acc-1\" id=\"ui-e-wofuer-wird-eine-bodenfolie-unter-industrieboeden-verwendet\">\n\n                    <h4 class=\"ui-e-accordion-title ui-e-title ui-right\">\n\n                                                    <span class=\"ui-e-accordion-icon ui-e-icon ui-e-right\" aria-hidden=\"true\">\n\n                                <span class=\"ui-e-accordion-icon-closed\">\n                                    <i aria-hidden=\"true\" class=\"ti ti-plus\"><\/i>                                <\/span>\n\n                                                                    <span class=\"ui-e-accordion-icon-opened\">\n                                        <i aria-hidden=\"true\" class=\"ti ti-minus\"><\/i>                                    <\/span>\n                                \n                            <\/span>\n                        \n                                                <span class=\"ui-e-accordion-title-text ui-e-title-text\" >\n                                                        End\u00fcstriyel zeminlerde zemin folyesi ne ama\u00e7la kullan\u0131l\u0131r?                        <\/span>\n\n                    <\/h4>\n\n                    <div class=\"ui-e-accordion-content ui-e-content\" style=\"\" aria-labelledby=\"ui-e-wofuer-wird-eine-bodenfolie-unter-industrieboeden-verwendet\" id=\"ui-e-acc-1\">\n                        Zemin folyeleri, alt zemin ile beton aras\u0131nda ay\u0131r\u0131c\u0131 ve kayd\u0131r\u0131c\u0131 katman g\u00f6revi g\u00f6r\u00fcr. End\u00fcstriyel zeminlerin uygulanmas\u0131n\u0131 ve sertle\u015fmesini destekler.                    <\/div>\n\n                <\/div>\n                            <div class=\"ui-e-accordion-item ui-e-item\" role=\"button\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ui-e-acc-2\" id=\"ui-e-was-bedeutet-pe-toleranzfolie\">\n\n                    <h4 class=\"ui-e-accordion-title ui-e-title ui-right\">\n\n                                                    <span class=\"ui-e-accordion-icon ui-e-icon ui-e-right\" aria-hidden=\"true\">\n\n                                <span class=\"ui-e-accordion-icon-closed\">\n                                    <i aria-hidden=\"true\" class=\"ti ti-plus\"><\/i>                                <\/span>\n\n                                                                    <span class=\"ui-e-accordion-icon-opened\">\n                                        <i aria-hidden=\"true\" class=\"ti ti-minus\"><\/i>                                    <\/span>\n                                \n                            <\/span>\n                        \n                                                <span class=\"ui-e-accordion-title-text ui-e-title-text\" >\n                                                        PE tolerans folyesi ne anlama gelir?                        <\/span>\n\n                    <\/h4>\n\n                    <div class=\"ui-e-accordion-content ui-e-content\" style=\"display:none;\" aria-labelledby=\"ui-e-was-bedeutet-pe-toleranzfolie\" id=\"ui-e-acc-2\">\n                        PE tolerans folyelerinde malzeme kal\u0131nl\u0131\u011f\u0131 a\u00e7\u0131s\u0131ndan belirli toleranslar kabul edilir. Kalite ise birim alan a\u011f\u0131rl\u0131\u011f\u0131na g\u00f6re tan\u0131mlan\u0131r.                    <\/div>\n\n                <\/div>\n                            <div class=\"ui-e-accordion-item ui-e-item\" role=\"button\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ui-e-acc-3\" id=\"ui-e-warum-ist-eine-trennlage-unter-beton-wichtig\">\n\n                    <h4 class=\"ui-e-accordion-title ui-e-title ui-right\">\n\n                                                    <span class=\"ui-e-accordion-icon ui-e-icon ui-e-right\" aria-hidden=\"true\">\n\n                                <span class=\"ui-e-accordion-icon-closed\">\n                                    <i aria-hidden=\"true\" class=\"ti ti-plus\"><\/i>                                <\/span>\n\n                                                                    <span class=\"ui-e-accordion-icon-opened\">\n                                        <i aria-hidden=\"true\" class=\"ti ti-minus\"><\/i>                                    <\/span>\n                                \n                            <\/span>\n                        \n                                                <span class=\"ui-e-accordion-title-text ui-e-title-text\" >\n                                                        Beton alt\u0131nda ay\u0131r\u0131c\u0131 katman neden \u00f6nemlidir?                        <\/span>\n\n                    <\/h4>\n\n                    <div class=\"ui-e-accordion-content ui-e-content\" style=\"display:none;\" aria-labelledby=\"ui-e-warum-ist-eine-trennlage-unter-beton-wichtig\" id=\"ui-e-acc-3\">\n                        Ay\u0131r\u0131c\u0131 katman, alt yap\u0131 malzemelerinin beton i\u00e7ine kar\u0131\u015fmas\u0131n\u0131 ve suyun alt zemine s\u0131zmas\u0131n\u0131 azaltmaya yard\u0131mc\u0131 olur.                    <\/div>\n\n                <\/div>\n                            <div class=\"ui-e-accordion-item ui-e-item\" role=\"button\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ui-e-acc-4\" id=\"ui-e-unterstuetzt-die-bodenfolie-den-schwindprozess-des-betons\">\n\n                    <h4 class=\"ui-e-accordion-title ui-e-title ui-right\">\n\n                                                    <span class=\"ui-e-accordion-icon ui-e-icon ui-e-right\" aria-hidden=\"true\">\n\n                                <span class=\"ui-e-accordion-icon-closed\">\n                                    <i aria-hidden=\"true\" class=\"ti ti-plus\"><\/i>                                <\/span>\n\n                                                                    <span class=\"ui-e-accordion-icon-opened\">\n                                        <i aria-hidden=\"true\" class=\"ti ti-minus\"><\/i>                                    <\/span>\n                                \n                            <\/span>\n                        \n                                                <span class=\"ui-e-accordion-title-text ui-e-title-text\" >\n                                                        Zemin folyesi betonun r\u00f6tre s\u00fcrecini destekler mi?                        <\/span>\n\n                    <\/h4>\n\n                    <div class=\"ui-e-accordion-content ui-e-content\" style=\"display:none;\" aria-labelledby=\"ui-e-unterstuetzt-die-bodenfolie-den-schwindprozess-des-betons\" id=\"ui-e-acc-4\">\n                        Evet, folye ayn\u0131 zamanda kayd\u0131r\u0131c\u0131 katman g\u00f6revi g\u00f6r\u00fcr ve kuruma s\u0131ras\u0131nda betonun do\u011fal r\u00f6tre s\u00fcrecini kolayla\u015ft\u0131r\u0131r.                    <\/div>\n\n                <\/div>\n                            <div class=\"ui-e-accordion-item ui-e-item\" role=\"button\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ui-e-acc-5\" id=\"ui-e-gibt-tecfin-eine-fachberatung-zur-anwendung\">\n\n                    <h4 class=\"ui-e-accordion-title ui-e-title ui-right\">\n\n                                                    <span class=\"ui-e-accordion-icon ui-e-icon ui-e-right\" aria-hidden=\"true\">\n\n                                <span class=\"ui-e-accordion-icon-closed\">\n                                    <i aria-hidden=\"true\" class=\"ti ti-plus\"><\/i>                                <\/span>\n\n                                                                    <span class=\"ui-e-accordion-icon-opened\">\n                                        <i aria-hidden=\"true\" class=\"ti ti-minus\"><\/i>                                    <\/span>\n                                \n                            <\/span>\n                        \n                                                <span class=\"ui-e-accordion-title-text ui-e-title-text\" >\n                                                        TECFIN uygulama konusunda teknik dan\u0131\u015fmanl\u0131k sunuyor mu?                        <\/span>\n\n                    <\/h4>\n\n                    <div class=\"ui-e-accordion-content ui-e-content\" style=\"display:none;\" aria-labelledby=\"ui-e-gibt-tecfin-eine-fachberatung-zur-anwendung\" id=\"ui-e-acc-5\">\n                        TECFIN, \u00f6neriler, teknik destek ve \u00fcr\u00fcn bilgileriyle yard\u0131mc\u0131 olur. Belirli kullan\u0131m alan\u0131na uygunlu\u011fun de\u011ferlendirilmesi m\u00fc\u015fterinin sorumlulu\u011fundad\u0131r.                    <\/div>\n\n                <\/div>\n                    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b5e3fd e-flex e-con-boxed e-con e-parent\" data-id=\"3b5e3fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3cc3755 e-con-full e-flex e-con e-child\" data-id=\"3cc3755\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3905e28 ui-e-a-animate elementor-invisible elementor-widget elementor-widget-highlighted-text\" data-id=\"3905e28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"highlighted-text.default\">\n\t\t\t\t\t        <h2 class=\"ui-e--highlighted-text\">\n            <span class=\"ui-e-headline-text elementor-repeater-item-b68a653\">Size Uygun \u00c7\u00f6z\u00fcme Bu<\/span><span class=\"ui-e-headline-text elementor-repeater-item-eb9df43 ui-e-headline-color\">\n\t\t\t\t\t\t\t\t\t<span class=\"whitespace\"><\/span>\n                                    <span>\n                                        <span class=\"ui-e-headline-text ui-e-headline-highlighted\">\u015eekilde Ula\u015f\u0131yoruz<\/span><span class=\"uicore-svg-wrapper\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 500 150\" preserveaspectratio=\"none\"><\/svg><\/span><\/span> <span class=\"whitespace\"> <\/span><\/span>        <\/h2>\n    \t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8719151 e-con-full e-flex e-con e-child\" data-id=\"8719151\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2a52c46 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"2a52c46\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9e9ef7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b9e9ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-question\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M202.021 0C122.202 0 70.503 32.703 29.914 91.026c-7.363 10.58-5.093 25.086 5.178 32.874l43.138 32.709c10.373 7.865 25.132 6.026 33.253-4.148 25.049-31.381 43.63-49.449 82.757-49.449 30.764 0 68.816 19.799 68.816 49.631 0 22.552-18.617 34.134-48.993 51.164-35.423 19.86-82.299 44.576-82.299 106.405V320c0 13.255 10.745 24 24 24h72.471c13.255 0 24-10.745 24-24v-5.773c0-42.86 125.268-44.645 125.268-160.627C377.504 66.256 286.902 0 202.021 0zM192 373.459c-38.196 0-69.271 31.075-69.271 69.271 0 38.195 31.075 69.27 69.271 69.27s69.271-31.075 69.271-69.271-31.075-69.27-69.271-69.27z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91d1a00 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"91d1a00\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;280&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f42baf elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5f42baf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">1<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e07d8a elementor-widget elementor-widget-heading\" data-id=\"7e07d8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Uygulama Alan\u0131<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67e9794 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"67e9794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2995\" data-end=\"3053\">Projenizi veya ihtiyac\u0131n\u0131z\u0131 k\u0131saca bize iletin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f944b5 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"5f944b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;360&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-333e8d8 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"333e8d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1094db elementor-widget elementor-widget-heading\" data-id=\"b1094db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Teknik Tavsiye<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40bb277 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"40bb277\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3119\" data-end=\"3179\">Uygun \u00fcr\u00fcnleri veya hizmetleri \u00f6neririz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3ed8c5 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"e3ed8c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;440&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57e0d46 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"57e0d46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">3<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23fd287 elementor-widget elementor-widget-heading\" data-id=\"23fd287\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Angebot \/ Datenblatt<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fc21d4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6fc21d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDok\u00fcmanlar\u0131 ve net bir \u00f6neriyi al\u0131rs\u0131n\u0131z.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-449b360 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"449b360\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;440&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a0de69 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7a0de69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">4<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad2cd6 elementor-widget elementor-widget-heading\" data-id=\"7ad2cd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Umsetzung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bfff35 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4bfff35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3360\" data-end=\"3412\">Projenizi birlikte ba\u015far\u0131yla ilerletelim.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79f5e16 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"79f5e16\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:&quot;520&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-444723e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"444723e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Bodenfolie f\u00fcr Industrieb\u00f6den Zuverl\u00e4ssige Trenn und Gleitschicht f\u00fcr stabile Betonfl\u00e4chen Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-549","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den entwickelt.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/tecfin.de\/tr\/bodenfolie\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"tr_TR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"TECFIN GmbH -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bodenfolie - TECFIN GmbH\" \/>\n\t\t<meta property=\"og:description\" content=\"Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den entwickelt.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tecfin.de\/tr\/bodenfolie\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/tecfin.de\/wp-content\/uploads\/tecfin_gmbh-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/tecfin.de\/wp-content\/uploads\/tecfin_gmbh-scaled.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-23T14:28:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-30T23:14:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bodenfolie - TECFIN GmbH\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den entwickelt.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/tecfin.de\/wp-content\/uploads\/tecfin_gmbh-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/bodenfolie\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tecfin.de\\\/tr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/bodenfolie\\\/#listItem\",\"name\":\"Bodenfolie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/bodenfolie\\\/#listItem\",\"position\":2,\"name\":\"Bodenfolie\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/#organization\",\"name\":\"TECFIN GmbH\",\"description\":\"TECFIN steht f\\u00fcr technische Produkte, fundierte Empfehlungen und L\\u00f6sungen, die Industrieb\\u00f6den dauerhaft leistungsf\\u00e4hig halten - im Neubau und im laufenden Betrieb.\",\"url\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/\",\"telephone\":\"+4935235362011\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tecfin.de\\\/wp-content\\\/uploads\\\/Tecfin_Logo2013-2.jpg\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/bodenfolie\\\/#organizationLogo\",\"width\":170,\"height\":179},\"image\":{\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/bodenfolie\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/bodenfolie\\\/#webpage\",\"url\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/bodenfolie\\\/\",\"name\":\"Bodenfolie - TECFIN GmbH\",\"description\":\"Die TECFIN Bodenfolie Typ 200 wurde speziell f\\u00fcr den Einsatz unter Industrieb\\u00f6den entwickelt.\",\"inLanguage\":\"tr-TR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/bodenfolie\\\/#breadcrumblist\"},\"datePublished\":\"2026-05-23T16:28:33+02:00\",\"dateModified\":\"2026-05-31T01:14:02+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/\",\"name\":\"TECFIN GmbH\",\"inLanguage\":\"tr-TR\",\"publisher\":{\"@id\":\"https:\\\/\\\/tecfin.de\\\/tr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Bodenfolie - TECFIN GmbH","description":"Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den entwickelt.","canonical_url":"https:\/\/tecfin.de\/tr\/bodenfolie\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/tecfin.de\/tr\/bodenfolie\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tecfin.de\/tr#listItem","position":1,"name":"Home","item":"https:\/\/tecfin.de\/tr","nextItem":{"@type":"ListItem","@id":"https:\/\/tecfin.de\/tr\/bodenfolie\/#listItem","name":"Bodenfolie"}},{"@type":"ListItem","@id":"https:\/\/tecfin.de\/tr\/bodenfolie\/#listItem","position":2,"name":"Bodenfolie","previousItem":{"@type":"ListItem","@id":"https:\/\/tecfin.de\/tr#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/tecfin.de\/tr\/#organization","name":"TECFIN GmbH","description":"TECFIN steht f\u00fcr technische Produkte, fundierte Empfehlungen und L\u00f6sungen, die Industrieb\u00f6den dauerhaft leistungsf\u00e4hig halten - im Neubau und im laufenden Betrieb.","url":"https:\/\/tecfin.de\/tr\/","telephone":"+4935235362011","logo":{"@type":"ImageObject","url":"https:\/\/tecfin.de\/wp-content\/uploads\/Tecfin_Logo2013-2.jpg","@id":"https:\/\/tecfin.de\/tr\/bodenfolie\/#organizationLogo","width":170,"height":179},"image":{"@id":"https:\/\/tecfin.de\/tr\/bodenfolie\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/tecfin.de\/tr\/bodenfolie\/#webpage","url":"https:\/\/tecfin.de\/tr\/bodenfolie\/","name":"Bodenfolie - TECFIN GmbH","description":"Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den entwickelt.","inLanguage":"tr-TR","isPartOf":{"@id":"https:\/\/tecfin.de\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/tecfin.de\/tr\/bodenfolie\/#breadcrumblist"},"datePublished":"2026-05-23T16:28:33+02:00","dateModified":"2026-05-31T01:14:02+02:00"},{"@type":"WebSite","@id":"https:\/\/tecfin.de\/tr\/#website","url":"https:\/\/tecfin.de\/tr\/","name":"TECFIN GmbH","inLanguage":"tr-TR","publisher":{"@id":"https:\/\/tecfin.de\/tr\/#organization"}}]},"og:locale":"tr_TR","og:site_name":"TECFIN GmbH -","og:type":"article","og:title":"Bodenfolie - TECFIN GmbH","og:description":"Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den entwickelt.","og:url":"https:\/\/tecfin.de\/tr\/bodenfolie\/","og:image":"https:\/\/tecfin.de\/wp-content\/uploads\/tecfin_gmbh-scaled.jpg","og:image:secure_url":"https:\/\/tecfin.de\/wp-content\/uploads\/tecfin_gmbh-scaled.jpg","article:published_time":"2026-05-23T14:28:33+00:00","article:modified_time":"2026-05-30T23:14:02+00:00","twitter:card":"summary_large_image","twitter:title":"Bodenfolie - TECFIN GmbH","twitter:description":"Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den entwickelt.","twitter:image":"https:\/\/tecfin.de\/wp-content\/uploads\/tecfin_gmbh-scaled.jpg"},"aioseo_meta_data":{"post_id":"549","title":null,"description":"Die TECFIN Bodenfolie Typ 200 wurde speziell f\u00fcr den Einsatz unter Industrieb\u00f6den entwickelt.","keywords":null,"keyphrases":{"focus":{"keyphrase":"Bodenfolie","score":82,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-05-30 22:52:27","updated":"2026-05-30 23:59:43"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tecfin.de\/tr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBodenfolie\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/tecfin.de\/tr"},{"label":"Bodenfolie","link":"https:\/\/tecfin.de\/tr\/bodenfolie\/"}],"_links":{"self":[{"href":"https:\/\/tecfin.de\/tr\/wp-json\/wp\/v2\/pages\/549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecfin.de\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tecfin.de\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tecfin.de\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecfin.de\/tr\/wp-json\/wp\/v2\/comments?post=549"}],"version-history":[{"count":10,"href":"https:\/\/tecfin.de\/tr\/wp-json\/wp\/v2\/pages\/549\/revisions"}],"predecessor-version":[{"id":653,"href":"https:\/\/tecfin.de\/tr\/wp-json\/wp\/v2\/pages\/549\/revisions\/653"}],"wp:attachment":[{"href":"https:\/\/tecfin.de\/tr\/wp-json\/wp\/v2\/media?parent=549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}